{"id":58983,"date":"2023-03-13T21:33:48","date_gmt":"2023-03-13T20:33:48","guid":{"rendered":"https:\/\/www.powermints.de\/?post_type=product&#038;p=58983"},"modified":"2026-01-03T12:02:05","modified_gmt":"2026-01-03T11:02:05","slug":"compass-intense-yellow","status":"publish","type":"product","link":"https:\/\/www.compass-mints.com\/en\/produkt\/compass-intense-yellow\/","title":{"rendered":"Compass Intense &#8211; Yellow"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;90px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding_tablet=&#8221;8%&#8221; bottom_padding_tablet=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;home&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;no-extra-padding&#8221; column_padding_phone=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;100&#8243; gradient_direction=&#8221;left_t_to_right_b&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; min_width=&#8221;47vh&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;5px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; enable_border_animation=&#8221;true&#8221;][vc_column_text]\n<h3>Die Pastille ist im Vergleich zur \u201eCompass Classic\u201c doppelt so gro\u00df. Durch die Verwendung von feinstem italienischem Pfefferminz\u00f6l und echtem nat\u00fcrlichen Zitronenextrakten, strotzt Compass Intense vor Geschmack. Die Pastille l\u00f6st sich langsamer im Mund auf und garantiert, noch l\u00e4nger, einen frischen Atem.<\/h3>\n[\/vc_column_text][vc_column_text]\n<ul>\n<li><strong>zuckerfrei mit S\u00fc\u00dfungsmitteln<\/strong><\/li>\n<li><strong>Aspartamfrei<\/strong><\/li>\n<li><strong>Acesulfame K frei<\/strong><\/li>\n<li><strong>glutenfrei und laktosefrei<\/strong><\/li>\n<li><strong>100% naturreine \u00e4therische \u00d6le<\/strong><\/li>\n<li><strong>f\u00fcr Vegetarier geeignet<\/strong><\/li>\n<li>Kann bei \u00fcberm\u00e4\u00dfigem Verzehr abf\u00fchrend wirken<\/li>\n<li>K\u00fchl und trocken lagern. Hergestellt in Deutschland<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; offset=&#8221;vc_col-xs-12&#8243;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;58776&#8243; background_image_position=&#8221;center center&#8221; background_image_stacking=&#8221;default&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.5&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;55vh&#8221; custom_height_tablet=&#8221;40vh&#8221; custom_height_phone=&#8221;300px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<div class=\"nectar-responsive-text font_size_min_16px font_size_desktop_1-1vw font_line_height_1-8\">\n<p>Lemon MINT hinterlassen garantiert ein erfrischendes und energetisierendes Mundgef\u00fchl. Jede Pastille wird sorgf\u00e4ltig mit reinen Zitronen hergestellt, um die perfekte Menge an zitronigem Zitronengeschmack zu bieten. Unser perfektes INTENSE Produkt f\u00fcr alle, die den Geschmack von frischen und spritzigen Zitrusfr\u00fcchten lieben.<\/p>\n<\/div>\n","protected":false},"featured_media":60715,"template":"","meta":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-58983","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-compass-intense","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/product\/58983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/media\/60715"}],"wp:attachment":[{"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/media?parent=58983"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/product_cat?post=58983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.compass-mints.com\/en\/wp-json\/wp\/v2\/product_tag?post=58983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}