{"id":60443,"date":"2024-10-28T12:05:32","date_gmt":"2024-10-28T11:05:32","guid":{"rendered":"https:\/\/www.compass-mints.com\/?p=60443"},"modified":"2024-10-28T12:05:32","modified_gmt":"2024-10-28T11:05:32","slug":"mut-zur-innovation-compass-intense-feiert-doppelsieg-bei-der-ism-middle-east","status":"publish","type":"post","link":"https:\/\/www.compass-mints.com\/de\/mut-zur-innovation-compass-intense-feiert-doppelsieg-bei-der-ism-middle-east\/","title":{"rendered":"Mut zur Innovation \u2013 Compass Intense feiert Doppelsieg bei der ISM Middle East"},"content":{"rendered":"<p>Wir\u00a0f\u00fchlen uns geehrt und freuen uns, bekannt geben zu k\u00f6nnen, dass Compass Intense auf der diesj\u00e4hrigen\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/ism-middle-east\/\">ISM Middle East<\/a> <strong>als bestes Hartbonbon<\/strong>\u00a0und\u00a0<strong>beste Verpackung<\/strong>\u00a0ausgezeichnet wurde !\u00a0Von nur acht Auszeichnungen hat unsere kleine, aber leidenschaftliche Marke zwei gewonnen, was zeigt, dass ein Engagement f\u00fcr Qualit\u00e4t und Authentizit\u00e4t in einer \u00fcberf\u00fcllten Branche wirklich herausragen kann.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-61024 alignright\" src=\"https:\/\/i0.wp.com\/www.powermints.de\/wp-content\/uploads\/2024\/10\/FullSizeRender-8.heic?resize=163%2C290&#038;ssl=1\" alt=\"\" width=\"163\" height=\"290\" \/><\/p>\n<p>Seit unseren Anf\u00e4ngen wird Compass Intense von einer einfachen Vision angetrieben: die Herstellung wundersch\u00f6n gestalteter Pfefferminzbonbons mit reinen, nat\u00fcrlichen Zutaten, die nachhaltig verpackt werden und etwas wirklich Besonderes bieten.\u00a0Diese Auszeichnungen spiegeln unser Engagement f\u00fcr diese Vision und unsere \u00dcberzeugung wider, dass die Verbraucher mehr verdienen als den Mainstream.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\" wp-image-61026 alignleft\" src=\"https:\/\/i0.wp.com\/www.powermints.de\/wp-content\/uploads\/2024\/10\/3417dcb9-6462-4f8f-a015-0f22526afa38-200x300.jpg?resize=141%2C212&#038;ssl=1\" alt=\"\" width=\"141\" height=\"212\" \/><\/p>\n<p>Gesch\u00e4ftsf\u00fchrer Jannis Theileis erkl\u00e4rte:\u00a0&#8222;Diese Anerkennung bedeutet uns sehr viel, aber noch wichtiger ist, dass sie das unglaubliche Team hinter Compass Intense feiert, das sein Herz in jedes Detail steckt.\u00a0Wir sind den Organisatoren der ISM und den Juroren dankbar, dass sie die Arbeit gesehen haben, die wir in Compass Intense gesteckt haben, und an den Wert dieses Produkts geglaubt haben.\u00a0Vielen Dank f\u00fcr die Anerkennung einer Marke, die unabh\u00e4ngig von ihrer Gr\u00f6\u00dfe danach strebt, etwas zu bewirken.&#8220;<\/p>\n<p>Wie immer bleibt unsere Botschaft die gleiche:\u00a0<strong>#RedirectYourMind<\/strong>.\u00a0Wir laden sowohl Einzelh\u00e4ndler als auch Verbraucher dazu ein, die Marken, die sie unterst\u00fctzen, zu \u00fcberdenken und Produkte zu w\u00e4hlen, die Sorgfalt, Qualit\u00e4t und ein Engagement f\u00fcr Inhaltsstoffe und Nachhaltigkeit widerspiegeln.\u00a0Mainstream zu fahren ist einfach.\u00a0Aber den Mut zu haben, etwas besser und anders zu machen, ist immer lohnender, macht mehr Spa\u00df und \u00f6ffnet oft neue T\u00fcren, die vorher verschlossen waren!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir\u00a0f\u00fchlen uns geehrt und freuen uns, bekannt geben zu k\u00f6nnen, dass Compass Intense auf der diesj\u00e4hrigen\u00a0ISM Middle East als bestes Hartbonbon\u00a0und\u00a0beste Verpackung\u00a0ausgezeichnet wurde !\u00a0Von nur acht Auszeichnungen hat unsere kleine,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":60440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-60443","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-compass-mints"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.compass-mints.com\/wp-content\/uploads\/2024\/10\/IMG_6074-2.heic?fit=%2C&ssl=1","_links":{"self":[{"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/posts\/60443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/comments?post=60443"}],"version-history":[{"count":1,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/posts\/60443\/revisions"}],"predecessor-version":[{"id":60444,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/posts\/60443\/revisions\/60444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/media\/60440"}],"wp:attachment":[{"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/media?parent=60443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/categories?post=60443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.compass-mints.com\/de\/wp-json\/wp\/v2\/tags?post=60443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}